{"id":1378,"date":"2017-10-24T04:20:59","date_gmt":"2017-10-24T04:20:59","guid":{"rendered":"http:\/\/demo.zozothemes.com\/roobia\/grid-with-details-copy\/"},"modified":"2024-05-25T11:56:47","modified_gmt":"2024-05-25T11:56:47","slug":"normal-slide-with-detail","status":"publish","type":"page","link":"https:\/\/demo.zozothemes.com\/roobia\/normal-slide-with-detail\/","title":{"rendered":"Normal Slide With Detail"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=&#8221;.vc_custom_1507986787256{padding-bottom: 0px !important;}&#8221;][vc_column]<div class=\"section-title-wrapper text-center shortcode-rand-1 roobia-inline-css\" data-css=\"&quot;.shortcode-rand-1 .title-separator.separator-border { background-color: #000000; }.shortcode-rand-1 .section-title { font-size: 76px; line-height: 76px; text-transform: capitalize; }&quot;\"><div class=\"title-wrap\"><span class=\"sub-title\">My Works<\/span><h1 class=\"section-title\">Roobia<\/h1><span class=\"title-separator separator-border theme-color-bg\"><\/span><\/div><!-- .title-wrap --><div class=\"section-description\">Lorem ipsum dolor sit amet, consectetur adipiscing elit.<br \/>\nSed varius neque non felis ultrices varius.<\/div><!-- .section-description --><\/div><!-- .section-title-wrapper -->[vc_row_inner css=&#8221;.vc_custom_1507986075900{padding-top: 40px !important;}&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;&#8221;]Temporibus autem quibusdam et aut officiis debitis aut rerum necessitatibus saepe eveniet ut et voluptates repudiandae sint et molestiae non recusandae. Et iusto odio dignissimos ducimus. Sed ut perspiciatis unde omnis iste natus error sit voluptatem accusantium doloremque laudantium, totam rem aperiam magni.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]Sed ut perspiciatis unde omnis iste natus error sit voluptatem. Qui officia deserunt mollit anim id est laborum. Excepteur sint occaecat cupidatat non proident, sunt in culpa. Nihil molestiae consequatur. Nemo enim ipsam voluptatem quia voluptas sit aspernatur aut odit aut fugit, sed quia consequuntur.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1508132072435{padding-top: 60px !important;}&#8221;][vc_column]<div class=\"portfolio-wrapper portfolio-classic\" data-css=\"&quot;&quot;\"><div class=\"owl-carousel portfolio-slide image-gallery\" data-loop=\"1\" data-margin=\"30\" data-center=\"0\" data-nav=\"1\" data-dots=\"0\" data-autoplay=\"1\" data-items=\"3\" data-items-tab=\"1\" data-items-mob=\"1\" data-duration=\"5000\" data-smartspeed=\"250\" data-scrollby=\"1\" data-autoheight=\"false\"><div class=\"item\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography21.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/woman-sitting\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/woman-sitting\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography21-400x267.jpg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography21-400x267.jpg\" height=\"400\" alt=\"\" \/><\/a><\/div><div class=\"portfolio-content-wrap\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography21.jpg\">Woman Sitting<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>Dark<\/span>,<span>Photography<\/span>,<span>Studio<\/span><\/div><div class=\"portfolio-excerpt\"><p><p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Donec dolor mauris, dictum non ligula eu,<\/p>\n<\/p><\/div><!-- .portfolio-excerpt --><\/div><!-- .portfolio-content-wrap --><\/div><!-- .portfolio-wrap --><\/div><!-- .item --><div class=\"item\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography20.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/photography\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/photography\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography20-400x267.jpg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography20-400x267.jpg\" height=\"400\" alt=\"\" \/><\/a><\/div><div class=\"portfolio-content-wrap\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography20.jpg\">Photography<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>Nature<\/span>,<span>People<\/span>,<span>Photography<\/span><\/div><div class=\"portfolio-excerpt\"><p><p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Donec dolor mauris, dictum non ligula eu,<\/p>\n<\/p><\/div><!-- .portfolio-excerpt --><\/div><!-- .portfolio-content-wrap --><\/div><!-- .portfolio-wrap --><\/div><!-- .item --><div class=\"item\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography19.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/glass-with-woman\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/glass-with-woman\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography19-400x267.jpg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography19-400x267.jpg\" height=\"400\" alt=\"\" \/><\/a><\/div><div class=\"portfolio-content-wrap\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography19.jpg\">Glass With Woman<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>High Key<\/span>,<span>Lightroom<\/span>,<span>Photography<\/span><\/div><div class=\"portfolio-excerpt\"><p><p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Donec dolor mauris, dictum non ligula eu,<\/p>\n<\/p><\/div><!-- .portfolio-excerpt --><\/div><!-- .portfolio-content-wrap --><\/div><!-- .portfolio-wrap --><\/div><!-- .item --><div class=\"item\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography18.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/black-woman\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/black-woman\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography18-400x267.jpg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography18-400x267.jpg\" height=\"400\" alt=\"\" \/><\/a><\/div><div class=\"portfolio-content-wrap\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography18.jpg\">Black Woman<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>Lightroom<\/span>,<span>Studio<\/span>,<span>Wild<\/span><\/div><div class=\"portfolio-excerpt\"><p><p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Donec dolor mauris, dictum non ligula eu,<\/p>\n<\/p><\/div><!-- .portfolio-excerpt --><\/div><!-- .portfolio-content-wrap --><\/div><!-- .portfolio-wrap --><\/div><!-- .item --><div class=\"item\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography17.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/man-in-blue-space\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/man-in-blue-space\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography17-400x267.jpg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography17-400x267.jpg\" height=\"400\" alt=\"\" \/><\/a><\/div><div class=\"portfolio-content-wrap\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography17.jpg\">Man in blue Space<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>Nature<\/span>,<span>Studio<\/span>,<span>Wild<\/span><\/div><div class=\"portfolio-excerpt\"><p><p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Donec dolor mauris, dictum non ligula eu,<\/p>\n<\/p><\/div><!-- .portfolio-excerpt --><\/div><!-- .portfolio-content-wrap --><\/div><!-- .portfolio-wrap --><\/div><!-- .item --><div class=\"item\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography12.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/lightroom\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/lightroom\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography12-400x267.jpg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography12-400x267.jpg\" height=\"400\" alt=\"\" \/><\/a><\/div><div class=\"portfolio-content-wrap\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography12.jpg\">Lightroom<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>Dark<\/span>,<span>High Key<\/span>,<span>Lightroom<\/span>,<span>People<\/span><\/div><div class=\"portfolio-excerpt\"><p><p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Donec dolor mauris, dictum non ligula eu,<\/p>\n<\/p><\/div><!-- .portfolio-excerpt --><\/div><!-- .portfolio-content-wrap --><\/div><!-- .portfolio-wrap --><\/div><!-- .item --><\/div><!-- .owl-carousel --><\/div><!-- .portfolio-wrapper -->[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1507986787256{padding-bottom: 0px !important;}&#8221;][vc_column][vc_row_inner css=&#8221;.vc_custom_1507986075900{padding-top: 40px !important;}&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;&#8221;]Temporibus autem quibusdam et aut officiis debitis<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1378","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/pages\/1378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/comments?post=1378"}],"version-history":[{"count":0,"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/pages\/1378\/revisions"}],"wp:attachment":[{"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/media?parent=1378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}