{"id":1220,"date":"2017-10-20T13:01:39","date_gmt":"2017-10-20T13:01:39","guid":{"rendered":"http:\/\/demo.zozothemes.com\/roobia\/grid-3-columns-copy\/"},"modified":"2024-05-25T11:34:48","modified_gmt":"2024-05-25T11:34:48","slug":"grid-default-style","status":"publish","type":"page","link":"https:\/\/demo.zozothemes.com\/roobia\/grid-default-style\/","title":{"rendered":"Grid Default Style"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=&#8221;.vc_custom_1507986787256{padding-bottom: 0px !important;}&#8221;][vc_column]<div class=\"section-title-wrapper text-center shortcode-rand-1 roobia-inline-css\" data-css=\"&quot;.shortcode-rand-1 .title-separator.separator-border { background-color: #000000; }.shortcode-rand-1 .section-title { font-size: 76px; line-height: 76px; text-transform: capitalize; }&quot;\"><div class=\"title-wrap\"><span class=\"sub-title\">My Works<\/span><h1 class=\"section-title\">Roobia<\/h1><span class=\"title-separator separator-border theme-color-bg\"><\/span><\/div><!-- .title-wrap --><div class=\"section-description\">Lorem ipsum dolor sit amet, consectetur adipiscing elit.<br \/>\nSed varius neque non felis ultrices varius.<\/div><!-- .section-description --><\/div><!-- .section-title-wrapper -->[vc_row_inner css=&#8221;.vc_custom_1507986075900{padding-top: 40px !important;}&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;&#8221;]Temporibus autem quibusdam et aut officiis debitis aut rerum necessitatibus saepe eveniet ut et voluptates repudiandae sint et molestiae non recusandae. Et iusto odio dignissimos ducimus. Sed ut perspiciatis unde omnis iste natus error sit voluptatem accusantium doloremque laudantium, totam rem aperiam magni.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]Sed ut perspiciatis unde omnis iste natus error sit voluptatem. Qui officia deserunt mollit anim id est laborum. Excepteur sint occaecat cupidatat non proident, sunt in culpa. Nihil molestiae consequatur. Nemo enim ipsam voluptatem quia voluptas sit aspernatur aut odit aut fugit, sed quia consequuntur.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1508132072435{padding-top: 60px !important;}&#8221;][vc_column]<div class=\"portfolio-wrapper shortcode-rand-2 roobia-inline-css\" data-css=\"&quot;.shortcode-rand-2 .portfolio-wrap { color: #ffffff; }.shortcode-rand-2 .portfolio-wrap a { color: #ffffff; }.shortcode-rand-2 .portfolio-wrap a:hover { color: #0057ff; }&quot;\"><div class=\"portfolio-filter filter-2\"><ul class=\"nav m-auto d-block text-center\"><li class=\"active\"><a href=\"#\" class=\"portfolio-filter-item\">All<\/a><\/li><li><a href=\"#\" class=\"portfolio-filter-item\" data-filter=\".portfolio-filter-20\">Dark<\/a><\/li><li><a href=\"#\" class=\"portfolio-filter-item\" data-filter=\".portfolio-filter-25\">High Key<\/a><\/li><li><a href=\"#\" class=\"portfolio-filter-item\" data-filter=\".portfolio-filter-33\">People<\/a><\/li><li><a href=\"#\" class=\"portfolio-filter-item\" data-filter=\".portfolio-filter-34\">Photography<\/a><\/li><li><a href=\"#\" class=\"portfolio-filter-item\" data-filter=\".portfolio-filter-40\">Studio<\/a><\/li><\/ul><\/div><!-- .portfolio-filter --><div class=\"image-gallery grid-layout portfolio-grid-layout\" style=\"margin-bottom: -20px;\" data-filter-stat=\"1\" data-first-cat=\"\"><div class=\"isotope\" data-cols=\"3\" data-gutter=\"20\" data-layout=\"fitRows\" data-infinite=\"false\"><article id=\"post-181\" class=\"vc-portfolio portfolio-default portfolio-filter-20 portfolio-filter-34 portfolio-filter-40\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography21.jpg\">Woman Sitting<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>Dark<\/span>,<span>Photography<\/span>,<span>Studio<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography21.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/woman-sitting\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/woman-sitting\/\"><img loading=\"lazy\" decoding=\"async\" width=\"440\" height=\"260\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography21-440x260.jpg\" class=\"img-fluid wp-post-image\" alt=\"\" srcset=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography21-440x260.jpg 440w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography21-768x456.jpg 768w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography21-1170x694.jpg 1170w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography21-390x231.jpg 390w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography21-220x130.jpg 220w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><article id=\"post-180\" class=\"vc-portfolio portfolio-default portfolio-filter-31 portfolio-filter-33 portfolio-filter-34\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography20.jpg\">Photography<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>Nature<\/span>,<span>People<\/span>,<span>Photography<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography20.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/photography\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/photography\/\"><img loading=\"lazy\" decoding=\"async\" width=\"440\" height=\"260\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography20-440x260.jpg\" class=\"img-fluid wp-post-image\" alt=\"\" srcset=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography20-440x260.jpg 440w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography20-768x456.jpg 768w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography20-1170x694.jpg 1170w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography20-390x231.jpg 390w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography20-220x130.jpg 220w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><article id=\"post-179\" class=\"vc-portfolio portfolio-default portfolio-filter-25 portfolio-filter-27 portfolio-filter-34\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography19.jpg\">Glass With Woman<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>High Key<\/span>,<span>Lightroom<\/span>,<span>Photography<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography19.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/glass-with-woman\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/glass-with-woman\/\"><img loading=\"lazy\" decoding=\"async\" width=\"440\" height=\"260\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography19-440x260.jpg\" class=\"img-fluid wp-post-image\" alt=\"\" srcset=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography19-440x260.jpg 440w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography19-768x456.jpg 768w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography19-1170x694.jpg 1170w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography19-390x231.jpg 390w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography19-220x130.jpg 220w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><article id=\"post-178\" class=\"vc-portfolio portfolio-default portfolio-filter-27 portfolio-filter-40 portfolio-filter-42\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography18.jpg\">Black Woman<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>Lightroom<\/span>,<span>Studio<\/span>,<span>Wild<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography18.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/black-woman\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/black-woman\/\"><img loading=\"lazy\" decoding=\"async\" width=\"440\" height=\"260\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography18-440x260.jpg\" class=\"img-fluid wp-post-image\" alt=\"\" srcset=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography18-440x260.jpg 440w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography18-768x456.jpg 768w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography18-1170x694.jpg 1170w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography18-390x231.jpg 390w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography18-220x130.jpg 220w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><article id=\"post-177\" class=\"vc-portfolio portfolio-default portfolio-filter-31 portfolio-filter-40 portfolio-filter-42\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography17.jpg\">Man in blue Space<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>Nature<\/span>,<span>Studio<\/span>,<span>Wild<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography17.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/man-in-blue-space\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/man-in-blue-space\/\"><img loading=\"lazy\" decoding=\"async\" width=\"440\" height=\"260\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography17-440x260.jpg\" class=\"img-fluid wp-post-image\" alt=\"\" srcset=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography17-440x260.jpg 440w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography17-768x456.jpg 768w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography17-1170x694.jpg 1170w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography17-390x231.jpg 390w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography17-220x130.jpg 220w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><article id=\"post-176\" class=\"vc-portfolio portfolio-default portfolio-filter-20 portfolio-filter-25 portfolio-filter-27 portfolio-filter-33\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography12.jpg\">Lightroom<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>Dark<\/span>,<span>High Key<\/span>,<span>Lightroom<\/span>,<span>People<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography12.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/lightroom\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/lightroom\/\"><img loading=\"lazy\" decoding=\"async\" width=\"440\" height=\"260\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography12-440x260.jpg\" class=\"img-fluid wp-post-image\" alt=\"\" srcset=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography12-440x260.jpg 440w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography12-768x456.jpg 768w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography12-1170x694.jpg 1170w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography12-390x231.jpg 390w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography12-220x130.jpg 220w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><article id=\"post-175\" class=\"vc-portfolio portfolio-default portfolio-filter-25 portfolio-filter-31 portfolio-filter-33 portfolio-filter-40\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography13.jpg\">Beauty Model<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>High Key<\/span>,<span>Nature<\/span>,<span>People<\/span>,<span>Studio<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography13.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/beauty-model\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/beauty-model\/\"><img loading=\"lazy\" decoding=\"async\" width=\"440\" height=\"260\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography13-440x260.jpg\" class=\"img-fluid wp-post-image\" alt=\"\" srcset=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography13-440x260.jpg 440w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography13-768x456.jpg 768w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography13-1170x694.jpg 1170w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography13-390x231.jpg 390w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography13-220x130.jpg 220w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><article id=\"post-174\" class=\"vc-portfolio portfolio-default portfolio-filter-20 portfolio-filter-25 portfolio-filter-33\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography14.jpg\">Luminosity<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>Dark<\/span>,<span>High Key<\/span>,<span>People<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography14.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/luminosity\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/luminosity\/\"><img loading=\"lazy\" decoding=\"async\" width=\"440\" height=\"260\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography14-440x260.jpg\" class=\"img-fluid wp-post-image\" alt=\"\" srcset=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography14-440x260.jpg 440w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography14-768x456.jpg 768w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography14-1170x694.jpg 1170w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography14-390x231.jpg 390w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography14-220x130.jpg 220w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><article id=\"post-171\" class=\"vc-portfolio portfolio-default portfolio-filter-20 portfolio-filter-31 portfolio-filter-34\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography11.jpg\">Tripod With Camera<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>Dark<\/span>,<span>Nature<\/span>,<span>Photography<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography11.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/tripod-with-camera\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/tripod-with-camera\/\"><img loading=\"lazy\" decoding=\"async\" width=\"440\" height=\"260\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography11-440x260.jpg\" class=\"img-fluid wp-post-image\" alt=\"\" srcset=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography11-440x260.jpg 440w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography11-768x456.jpg 768w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography11-1170x694.jpg 1170w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography11-390x231.jpg 390w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography11-220x130.jpg 220w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><article id=\"post-172\" class=\"vc-portfolio portfolio-default portfolio-filter-20 portfolio-filter-34 portfolio-filter-40\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography16.jpg\">Stylist Photographer<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>Dark<\/span>,<span>Photography<\/span>,<span>Studio<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography16.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/stylist-photographer\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/stylist-photographer\/\"><img loading=\"lazy\" decoding=\"async\" width=\"440\" height=\"260\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography16-440x260.jpg\" class=\"img-fluid wp-post-image\" alt=\"\" srcset=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography16-440x260.jpg 440w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography16-768x456.jpg 768w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography16-1170x694.jpg 1170w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography16-390x231.jpg 390w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography16-220x130.jpg 220w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><article id=\"post-173\" class=\"vc-portfolio portfolio-default portfolio-filter-20 portfolio-filter-25 portfolio-filter-34 portfolio-filter-42\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography15.jpg\">Studio Shot<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>Dark<\/span>,<span>High Key<\/span>,<span>Photography<\/span>,<span>Wild<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography15.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/studio-shot\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/studio-shot\/\"><img loading=\"lazy\" decoding=\"async\" width=\"440\" height=\"260\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography15-440x260.jpg\" class=\"img-fluid wp-post-image\" alt=\"\" srcset=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography15-440x260.jpg 440w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography15-768x456.jpg 768w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography15-1170x694.jpg 1170w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography15-390x231.jpg 390w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography15-220x130.jpg 220w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><article id=\"post-170\" class=\"vc-portfolio portfolio-default portfolio-filter-31 portfolio-filter-40 portfolio-filter-42\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography10.jpg\">Photo Of Wilderness<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>Nature<\/span>,<span>Studio<\/span>,<span>Wild<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography10.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/photo-of-wilderness\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/photo-of-wilderness\/\"><img loading=\"lazy\" decoding=\"async\" width=\"440\" height=\"260\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography10-440x260.jpg\" class=\"img-fluid wp-post-image\" alt=\"\" srcset=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography10-440x260.jpg 440w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography10-768x456.jpg 768w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography10-1170x694.jpg 1170w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography10-390x231.jpg 390w, https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/09\/photography10-220x130.jpg 220w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><\/div><!-- .isotope --><\/div><!-- .grid-layout --><\/div><!-- portfolio-wrapper -->[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1507986787256{padding-bottom: 0px !important;}&#8221;][vc_column][vc_row_inner css=&#8221;.vc_custom_1507986075900{padding-top: 40px !important;}&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;&#8221;]Temporibus autem quibusdam et aut officiis debitis aut rerum necessitatibus saepe eveniet ut et voluptates repudiandae sint et molestiae non recusandae. Et iusto odio dignissimos ducimus. Sed ut perspiciatis unde omnis iste natus error sit voluptatem accusantium doloremque laudantium, totam rem aperiam magni.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]Sed ut perspiciatis unde<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1220","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/pages\/1220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/comments?post=1220"}],"version-history":[{"count":0,"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/pages\/1220\/revisions"}],"wp:attachment":[{"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/media?parent=1220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}