{"id":1203,"date":"2017-10-20T12:38:17","date_gmt":"2017-10-20T12:38:17","guid":{"rendered":"http:\/\/demo.zozothemes.com\/roobia\/grid-fullwidth-copy\/"},"modified":"2017-10-20T12:38:17","modified_gmt":"2017-10-20T12:38:17","slug":"masonry-fullwidth","status":"publish","type":"page","link":"https:\/\/demo.zozothemes.com\/roobia\/masonry-fullwidth\/","title":{"rendered":"Masonry Fullwidth"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8221;stretch_row_content&#8221; css=&#8221;.vc_custom_1508503208517{padding-bottom: 0px !important;}&#8221;][vc_column]<div class=\"section-title-wrapper text-center shortcode-rand-1 roobia-inline-css\" data-css=\"&quot;.shortcode-rand-1 .title-separator.separator-border { background-color: #000000; }.shortcode-rand-1 .section-title { font-size: 76px; line-height: 76px; text-transform: capitalize; }&quot;\"><div class=\"title-wrap\"><span class=\"sub-title\">My Works<\/span><h1 class=\"section-title\">Roobia<\/h1><span class=\"title-separator separator-border theme-color-bg\"><\/span><\/div><!-- .title-wrap --><div class=\"section-description\">Lorem ipsum dolor sit amet, consectetur adipiscing elit.<br \/>\nSed varius neque non felis ultrices varius.<\/div><!-- .section-description --><\/div><!-- .section-title-wrapper -->[vc_row_inner css=&#8221;.vc_custom_1507986075900{padding-top: 40px !important;}&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]Temporibus autem quibusdam et aut officiis debitis aut rerum necessitatibus saepe eveniet ut et voluptates repudiandae sint et molestiae non recusandae. Et iusto odio dignissimos ducimus. Sed ut perspiciatis unde omnis iste natus error sit voluptatem accusantium doloremque laudantium, totam rem aperiam magni dolores eos.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]Sed ut perspiciatis unde omnis iste natus error sit voluptatem. Qui officia deserunt mollit anim id est laborum. Excepteur sint occaecat cupidatat non proident, sunt in culpa. Nihil molestiae consequatur. Nemo enim ipsam voluptatem quia voluptas sit aspernatur aut odit aut fugit, sed quia consequuntur.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221; css=&#8221;.vc_custom_1508499318872{padding-top: 60px !important;}&#8221;][vc_column]<div class=\"portfolio-wrapper shortcode-rand-2 roobia-inline-css\" data-css=\"&quot;.shortcode-rand-2 .portfolio-wrap { color: #ffffff; }.shortcode-rand-2 .portfolio-wrap a { color: #ffffff; }.shortcode-rand-2 .portfolio-wrap a:hover { color: #0057ff; }&quot;\"><div class=\"portfolio-filter filter-2\"><ul class=\"nav m-auto d-block text-center\"><li class=\"active\"><a href=\"#\" class=\"portfolio-filter-item\">All<\/a><\/li><li><a href=\"#\" class=\"portfolio-filter-item\" data-filter=\".portfolio-filter-17\">Black and White<\/a><\/li><li><a href=\"#\" class=\"portfolio-filter-item\" data-filter=\".portfolio-filter-30\">Minimal<\/a><\/li><li><a href=\"#\" class=\"portfolio-filter-item\" data-filter=\".portfolio-filter-28\">Macro<\/a><\/li><li><a href=\"#\" class=\"portfolio-filter-item\" data-filter=\".portfolio-filter-19\">City<\/a><\/li><li><a href=\"#\" class=\"portfolio-filter-item\" data-filter=\".portfolio-filter-15\">Animals<\/a><\/li><\/ul><\/div><!-- .portfolio-filter --><div class=\"image-gallery grid-layout portfolio-masonry-layout\" style=\"margin-bottom: -15px;\" data-filter-stat=\"1\" data-first-cat=\"\"><div class=\"isotope\" data-cols=\"3\" data-gutter=\"15\" data-layout=\"masonry\" data-infinite=\"true\"><article id=\"post-1092\" class=\"vc-portfolio portfolio-angle portfolio-filter-22 portfolio-filter-30\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-1.jpg\">Minimal Plants<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>Flower<\/span>,<span>Minimal<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-1.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/minimal-plants\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/minimal-plants\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-1-400x400.jpg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-1-400x400.jpg\" height=\"400\" alt=\"\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><article id=\"post-1090\" class=\"vc-portfolio portfolio-angle portfolio-filter-19 portfolio-filter-28\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-2.jpg\">Interior Ceiling<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>City<\/span>,<span>Macro<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-2.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/interior-ceiling\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/interior-ceiling\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-2-400x220.jpg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-2-400x220.jpg\" height=\"400\" alt=\"\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><article id=\"post-1091\" class=\"vc-portfolio portfolio-angle portfolio-filter-30 portfolio-filter-41\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-7.jpeg\">Nature of girl<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>Minimal<\/span>,<span>Vertical<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-7.jpeg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/nature-of-girl\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/nature-of-girl\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-7-400x610.jpeg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-7-400x610.jpeg\" height=\"400\" alt=\"\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><article id=\"post-1089\" class=\"vc-portfolio portfolio-angle portfolio-filter-22 portfolio-filter-28\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-3.jpg\">Minimal Fruits<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>Flower<\/span>,<span>Macro<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-3.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/minimal-fruits\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/minimal-fruits\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-3-400x220.jpg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-3-400x220.jpg\" height=\"400\" alt=\"\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><article id=\"post-1087\" class=\"vc-portfolio portfolio-angle portfolio-filter-17 portfolio-filter-30\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-5.jpg\">The Wall Street<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>Black and White<\/span>,<span>Minimal<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-5.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/the-wall-street\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/the-wall-street\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-5-400x220.jpg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-5-400x220.jpg\" height=\"400\" alt=\"\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><article id=\"post-1088\" class=\"vc-portfolio portfolio-angle portfolio-filter-19 portfolio-filter-28 portfolio-filter-30\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-4.jpg\">Winter Walks<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>City<\/span>,<span>Macro<\/span>,<span>Minimal<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-4.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/winter-walks\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/winter-walks\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-4-400x400.jpg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-4-400x400.jpg\" height=\"400\" alt=\"\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><article id=\"post-1086\" class=\"vc-portfolio portfolio-angle portfolio-filter-22 portfolio-filter-28\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-6.jpg\">Flowerpot<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>Flower<\/span>,<span>Macro<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-6.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/flowerpot\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/flowerpot\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-6-400x220.jpg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-6-400x220.jpg\" height=\"400\" alt=\"\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><article id=\"post-1085\" class=\"vc-portfolio portfolio-angle portfolio-filter-17 portfolio-filter-30\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-7.jpg\">Minimal Wall Desert<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>Black and White<\/span>,<span>Minimal<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-7.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/minimal-wall-desert\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/minimal-wall-desert\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-7-400x400.jpg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-7-400x400.jpg\" height=\"400\" alt=\"\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><article id=\"post-1084\" class=\"vc-portfolio portfolio-angle portfolio-filter-15 portfolio-filter-22\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-16.jpg\">Climate change<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>Animals<\/span>,<span>Flower<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-16.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/climate-change\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/climate-change\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-16-400x400.jpg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-16-400x400.jpg\" height=\"400\" alt=\"\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><article id=\"post-1083\" class=\"vc-portfolio portfolio-angle portfolio-filter-17 portfolio-filter-30\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-9.jpg\">Modern Discipleship<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>Black and White<\/span>,<span>Minimal<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-9.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/modern-discipleship\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/modern-discipleship\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-9-400x400.jpg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-9-400x400.jpg\" height=\"400\" alt=\"\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><article id=\"post-1082\" class=\"vc-portfolio portfolio-angle portfolio-filter-19 portfolio-filter-30\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-10.jpg\">Architecture<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>City<\/span>,<span>Minimal<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-10.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/architecture\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/architecture\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-10-400x400.jpg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-10-400x400.jpg\" height=\"400\" alt=\"\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><article id=\"post-1081\" class=\"vc-portfolio portfolio-angle portfolio-filter-19 portfolio-filter-28\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-11.jpg\">The Wall Light<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-categories\"><span>City<\/span>,<span>Macro<\/span><\/div><div class=\"portfolio-icons\"><p><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-11.jpg\" class=\"image-gallery-link zoom-icon\"><i class=\"icon-magnifier-add\"><\/i><\/a><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/the-wall-light\/\" class=\"link-icon\"><i class=\"icon-link\"><\/i><\/a><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/the-wall-light\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-11-400x400.jpg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/mas-11-400x400.jpg\" height=\"400\" alt=\"\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/article><\/div><!-- .isotope --><\/div><!-- .grid-layout --><\/div><!-- portfolio-wrapper --><div class=\"infinite-load\"><div class=\"post-pagination-wrap\"><ul class=\"nav pagination post-pagination justify-content-center\"><li class=\"nav-item active\"><span class=\"active\">01<\/span><\/li><li class=\"nav-item\"><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/pages\/1203\/page\/2\/\">02<\/a><\/li><li class=\"nav-item\"><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/pages\/1203\/page\/2\/\" class=\"next-page\" title=\"next\">Next<\/a><\/li><li class=\"nav-item next\"><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/pages\/1203\/page\/2\/\" title=\"Last\">Last<\/a><\/li><\/ul><\/div><\/div><!-- infinite-load -->[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row_content&#8221; css=&#8221;.vc_custom_1508503208517{padding-bottom: 0px !important;}&#8221;][vc_column][vc_row_inner css=&#8221;.vc_custom_1507986075900{padding-top: 40px !important;}&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]Temporibus autem quibusdam et aut officiis debitis aut rerum necessitatibus saepe eveniet ut et voluptates repudiandae sint et molestiae non recusandae. Et iusto odio dignissimos ducimus. Sed ut perspiciatis unde omnis iste natus error sit voluptatem accusantium doloremque laudantium, totam rem aperiam magni dolores eos.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]Sed ut<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1203","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/pages\/1203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/comments?post=1203"}],"version-history":[{"count":0,"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/pages\/1203\/revisions"}],"wp:attachment":[{"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/media?parent=1203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}