{"id":1058,"date":"2017-10-17T05:03:06","date_gmt":"2017-10-17T05:03:06","guid":{"rendered":"http:\/\/demo.zozothemes.com\/roobia\/home-vertical-style-copy\/"},"modified":"2024-08-02T07:30:27","modified_gmt":"2024-08-02T07:30:27","slug":"sticky-vertical-slide","status":"publish","type":"page","link":"https:\/\/demo.zozothemes.com\/roobia\/sticky-vertical-slide\/","title":{"rendered":"Sticky Vertical Slide"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=&#8221;.vc_custom_1722583207283{padding-top: 0px !important;padding-right: 0px !important;padding-bottom: 0px !important;padding-left: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1508217085092{padding-right: 0px !important;padding-left: 0px !important;}&#8221;]<div class=\"portfolio-wrapper portfolio-creative\" data-css=\"&quot;&quot;\"><div class=\"owl-carousel portfolio-slide image-gallery\" data-loop=\"1\" data-margin=\"0\" data-center=\"0\" data-nav=\"1\" data-dots=\"0\" data-autoplay=\"1\" data-items=\"2\" data-items-tab=\"2\" data-items-mob=\"1\" data-duration=\"5000\" data-smartspeed=\"1000\" data-scrollby=\"1\" data-autoheight=\"false\"><div class=\"item\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-7.jpeg\">Nature of girl<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-icons\"><p><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/nature-of-girl\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-7-600x915.jpeg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-7-600x915.jpeg\" height=\"600\" alt=\"\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/div><!-- .item --><div class=\"item\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-5.jpeg\">Standing man see lake<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-icons\"><p><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/standing-man-see-lake\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-5-600x915.jpeg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-5-600x915.jpeg\" height=\"600\" alt=\"\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/div><!-- .item --><div class=\"item\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-7.jpeg\">Nature of love<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-icons\"><p><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/nature-of-love\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-7-600x915.jpeg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-7-600x915.jpeg\" height=\"600\" alt=\"\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/div><!-- .item --><div class=\"item\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-2.jpeg\">Nature of mountain<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-icons\"><p><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/people-eyes-copy\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-2-600x915.jpeg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-2-600x915.jpeg\" height=\"600\" alt=\"\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/div><!-- .item --><div class=\"item\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-1.jpeg\">People Eyes<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-icons\"><p><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/people-eyes\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-1-600x915.jpeg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-1-600x915.jpeg\" height=\"600\" alt=\"\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/div><!-- .item --><div class=\"item\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-11.jpeg\">Never Ending Search<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-icons\"><p><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/never-ending-search\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-11-600x915.jpeg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-11-600x915.jpeg\" height=\"600\" alt=\"\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/div><!-- .item --><div class=\"item\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-10.jpg\">Unlimited Choices<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-icons\"><p><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/unlimited-choices\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-10-600x915.jpg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-10-600x915.jpg\" height=\"600\" alt=\"\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/div><!-- .item --><div class=\"item\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-8.jpeg\">Someday Today<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-icons\"><p><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/someday-today\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-8-600x915.jpeg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-8-600x915.jpeg\" height=\"600\" alt=\"\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/div><!-- .item --><div class=\"item\"><div class=\"portfolio-wrap\"><div class=\"portfolio-img portfolio-overlay-wrap\"><div class=\"portfolio-overlay overlay-center\"><div class=\"portfolio-title\"><h3><a href=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-6.jpeg\">Portfolio Caption<\/a><\/h3><\/div><!-- .portfolio-title --><div class=\"portfolio-icons\"><p><\/p><\/div><!-- .portfolio-icons --><\/div><!-- .portfolio-overlay --><a href=\"https:\/\/demo.zozothemes.com\/roobia\/portfolio\/portfolio-caption\/\"><img decoding=\"async\" class=\"img-fluid cpt-img\" src=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-6-600x915.jpeg\" width=\"https:\/\/demo.zozothemes.com\/roobia\/wp-content\/uploads\/sites\/11\/2017\/10\/vertical-6-600x915.jpeg\" height=\"600\" alt=\"\" \/><\/a><\/div><\/div><!-- .portfolio-wrap --><\/div><!-- .item --><\/div><!-- .owl-carousel --><\/div><!-- .portfolio-wrapper -->[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1722583207283{padding-top: 0px !important;padding-right: 0px !important;padding-bottom: 0px !important;padding-left: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1508217085092{padding-right: 0px !important;padding-left: 0px !important;}&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1058","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/pages\/1058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/comments?post=1058"}],"version-history":[{"count":0,"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/pages\/1058\/revisions"}],"wp:attachment":[{"href":"https:\/\/demo.zozothemes.com\/roobia\/wp-json\/wp\/v2\/media?parent=1058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}